{"id":12058,"date":"2022-06-19T21:33:59","date_gmt":"2022-06-19T19:33:59","guid":{"rendered":"https:\/\/catalunyaturisme.cat\/?p=12058"},"modified":"2024-03-24T22:38:24","modified_gmt":"2024-03-24T21:38:24","slug":"vielha","status":"publish","type":"post","link":"https:\/\/catalunyaturisme.cat\/es\/vielha\/","title":{"rendered":"Vielha, la villa m\u00e1s cosmopolita del Valle de Ar\u00e1n"},"content":{"rendered":"<p><strong>Vielha<\/strong>, la capital del Valle de Ar\u00e1n, es una villa pirenaica que se encuentra a casi 1.000 metros de altitud y est\u00e1 rodeada de picos que superan los 2.000 metros. Esta pintoresca localidad se caracteriza por sus edificios de piedra, t\u00edpicos del Valle de Ar\u00e1n, y uno de sus tesoros, el r\u00edo Nere, que atraviesa la localidad.<\/p><h2>Qu\u00e9 ver<\/h2><p>El casco hist\u00f3rico de la ciudad se encuentra cerca de la confluencia entre el r\u00edo Nere y el r\u00edo Garona. Esta cautivadora parte de la villa destaca por sus <strong>calles estrechas y sus hist\u00f3ricos edificios<\/strong>.<\/p><p>Uno de los lugares m\u00e1s emblem\u00e1ticos del casco antiguo de la ciudad es la <strong>iglesia de San Miquel de Vielha<\/strong>. Esta edificaci\u00f3n se caracteriza por su estilo rom\u00e1nico, que comienza a mostrar algunos rasgos t\u00edpicos del estilo g\u00f3tico. Su campanario llama mucho la atenci\u00f3n por su tama\u00f1o, pero hay que tener en cuenta que esta iglesia se construy\u00f3 al lado del castillo medieval y, por esta raz\u00f3n, el campanario tambi\u00e9n ten\u00eda la funci\u00f3n de torre de defensa y de homenaje. Actualmente, esta iglesia se encuentra al lado del Ayuntamiento y la Oficina de Turismo, y en su interior se conservan el Cristo de Mijaran y una peque\u00f1a colecci\u00f3n de pinturas g\u00f3ticas y barrocas.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27218\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-esglesia-sant-miqueu-1024x706.jpg\" alt=\"\" width=\"1024\" height=\"706\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-miqueu-1024x706.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-miqueu-300x207.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-miqueu-768x529.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-miqueu.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Otro de los atractivos de la villa es <em><strong>\u00c7\u00f2 de Rod\u00e8s<\/strong><\/em>, que se encuentra en la calle Mayor. Esta casa de 1608 conserva a\u00fan muchos elementos del pasado como las esquinas de piedra, la puerta adovelada y las dos ventanas del piso superior: una de ellas de estilo g\u00f3tico y la otra de arco rebajado.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27206\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-casa-rodes-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-casa-rodes-1024x768.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-casa-rodes-300x225.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-casa-rodes-768x576.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-casa-rodes.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Otra de las casas del g\u00f3tico medieval que encontramos en Vielha es la <strong><i>\u00c7\u00f2 de Fed<\/i><em>usa<\/em><\/strong>. Tambi\u00e9n en la calle Mayor, integra dos casas adosadas de tejados de madera y pizarra. En el portal se pueden observar el m\u00e1rmol y el dintel. Sobre la puerta hay un ventanal renacentista, con molduras e impostas.<sup id=\"cite_ref-ipac_2-0\" class=\"reference\"><\/sup><\/p><p>Adem\u00e1s, para conocer una casa t\u00edpica aranesa podemos pasar por delante de <em><strong>\u00c7\u00f2 de Saperisa<\/strong><\/em>, una de las casas m\u00e1s hist\u00f3ricas de Vielha que data de 1605. En la fachada de este edificio se pueden ver dos grandes puertas de madera y varias ventanas con rejas.<\/p><p>Adem\u00e1s, en la <strong>calle Mayor<\/strong> de Vielha tambi\u00e9n encontraremos <strong><em>Tor deth generau Martinhon<\/em><\/strong>, una casa se\u00f1orial que data de finales del siglo XVI. Dispone de una peque\u00f1a torre que hace esquina y destaca notablemente por sus esquinas de piedra.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27222\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-museu-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-museu-1024x768.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-museu-300x225.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-museu-768x576.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-museu.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Este territorio ha estado siempre muy vinculado con el agua por el r\u00edo que lo atraviesa: la Garona, y su afluente, el Nere. Para cruzarlos hay dos puentes hist\u00f3ricos, que permiten escuchar y ver c\u00f3mo baja esta agua. Uno de estos puentes es el <strong>Puente de madera de la Garona<\/strong>. El otro es el <strong>antiguo puente Medieval sobre el r\u00edo Nere<\/strong>.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27202\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-10-1024x759.jpg\" alt=\"\" width=\"1024\" height=\"759\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-10-1024x759.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-10-300x222.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-10-768x569.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-10.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Otro de los edificios importantes del casco hist\u00f3rico es la <em><strong>F\u00e1brica de la Lana<\/strong><\/em>, una industria textil de finales del siglo XIX que transformaba la lana natural en hilo de lana. Esta f\u00e1brica fue construida por un vecino de Vielha y funcion\u00f3 hasta mediados del siglo XX. La f\u00e1brica se nutr\u00eda de la fuerza motriz del r\u00edo Nere que mediante la fuerza de la corriente del agua mov\u00eda la rueda de madera que transmit\u00eda la energ\u00eda cin\u00e9tica a las m\u00e1quinas.<\/p><p>La importancia del agua para la ciudad tambi\u00e9n se puede ver reflejada en la <strong>fuente con el escudo de Ar\u00e1n<\/strong>, situada en el mismo centro de Vielha.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27226\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-placa-font-1024x732.jpg\" alt=\"\" width=\"1024\" height=\"732\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-placa-font-1024x732.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-placa-font-300x215.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-placa-font-768x549.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-placa-font.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><h2>Qu\u00e9 hacer<\/h2><p>La villa de Vielha es una ciudad que ha cambiado mucho durante los \u00faltimos a\u00f1os y se ha adaptado muy bien a la demanda tur\u00edstica para ofrecer tanto servicios, comercios destinados al turismo, como espacios culturales y equipamientos deportivos.<\/p><p>En la actualidad, el edificio de Tor deth generau Martinhon es la sede central de los Museos del Valle de Ar\u00e1n y all\u00ed encontraremos el <strong>Museo Etnol\u00f3gico<\/strong>, donde podremos aprender un poco m\u00e1s sobre la historia del Valle de Ar\u00e1n. Tambi\u00e9n ocupa otros espacios como la Casa Joanchiquet de Vilam\u00f2s y la iglesia de San Juan de <a href=\"https:\/\/catalunyaturisme.cat\/es\/arties\/\" title=\"Arties\">Arties<\/a>.<\/p><p>Para los amantes del turismo activo, dispone del <strong>Palai de G\u00e8u<\/strong>, una pista de hielo que cuenta con monitoreo para quien quiera iniciarse, piscina y salas de actividad.<\/p><p>Adem\u00e1s, hay muchas empresas que ofrecen la posibilidad de practicar <strong>deportes de aventura,<\/strong> rutas en 4X4 por el Valle de Ar\u00e1n y toda clase de deportes de invierno.<\/p><p>Si quieren hacer <strong>senderismo<\/strong>, pueden recorrer alguno de los itinerarios que comienzan en esta villa y que nos adentran en el coraz\u00f3n del Valle de Ar\u00e1n. El <em>Cam\u00edn de Reiau<\/em>, por ejemplo, lleva hacia el Alto Ar\u00e1n en un sentido, y hacia el Bajo Ar\u00e1n en el otro sentido.<\/p><h2>Gastronom\u00eda<\/h2><p>La gastronom\u00eda del Valle de Ar\u00e1n destaca por el uso de <strong>productos de elaboraci\u00f3n propia<\/strong>: hay muchos peque\u00f1os productores locales, talleres y obradores artesanales de elaboraci\u00f3n de <strong>quesos<\/strong> y yogures, <strong>embutidos<\/strong> (butifarra negra, chorizo, pat\u00e9), pan, mermeladas, vinagre de sidra, miel, conservas\u2026 Esto representa mucha calidad y pervivencia de los sabores tradicionales.<\/p><p>Entre los platos t\u00edpicos de la zona destacan los elaborados con animales de caza: la <strong>olla aranesa<\/strong>, un caldo con carne de cerdo, de ternera, pollo, pasta, legumbres y verduras; el <strong>confit de pato<\/strong> y el <strong>civet de jabal\u00ed<\/strong>.<\/p><figure id=\"attachment_24510\" aria-describedby=\"caption-attachment-24510\" style=\"width: 1024px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-24510\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/olla-aranesa3-1024x723.jpg\" alt=\"Olla aranesa\" width=\"1024\" height=\"723\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/olla-aranesa3-1024x723.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/olla-aranesa3-300x212.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/olla-aranesa3-768x542.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/olla-aranesa3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-24510\" class=\"wp-caption-text\">Olla aranesa &#8211; Restaurante Casa Turnay<\/figcaption><\/figure><p>En reposter\u00eda, se elaboran los <strong>corquilhons<\/strong>, unas pastas tradicionales fritas a base de harina y az\u00facar, y los <strong>tronquets<\/strong>, unas pastas con an\u00eds y forma de rombo, fritas y espolvoreadas con az\u00facar.<\/p><h2>D\u00f3nde comer<\/h2><p>En esta poblaci\u00f3n hay una gran cantidad de bares y restaurantes donde poder hacer una buena comida para recuperar fuerzas y continuar visitando el Valle. Se puede comer desde cocina tradicional a creativa y de autor.<\/p><p>Consulta todos los <a title=\"Restaurantes Vielha\" href=\"https:\/\/guiacat.cat\/es\/restaurantes\/ciudad\/vielha\" target=\"_blank\" rel=\"noopener\">restaurantes de Vielha en<\/a> <strong><a title=\"restaurantes boss\u00f2st\" href=\"https:\/\/guiacat.cat\/\" target=\"_blank\" rel=\"nofollow noopener\">Guiacat<\/a><\/strong>.<\/p><h2>D\u00f3nde dormir<\/h2><p>En Vielha encontrar\u00e9is muchos hoteles y alojamientos tur\u00edsticos donde pasar la noche. Hay para todo tipo de nivel adquisitivo. Entre todas las opciones, una muy buena opci\u00f3n es alojarse en una casa tradicional de monta\u00f1a para vivir la experiencia m\u00e1s aut\u00e9ntica del Valle de Ar\u00e1n y refugiarse del fr\u00edo o del calor.<\/p><p>Puedes encontrar los <a title=\"Casas rurales Valle de Ar\u00e1n\" href=\"https:\/\/rural.guiacat.cat\/https:\/\/rural.guiacat.cat\/es\/localitzacio\/val-daran\/localitzacio\/val-daran\" target=\"_blank\" rel=\"noopener\">alojamientos rurales del Valle de Ar\u00e1n en <strong>Guiacat<\/strong><\/a>.<\/p><h2>Fiestas<\/h2><p>La <strong>Fiesta Mayor de Vielha<\/strong> tiene lugar la segunda semana de septiembre, cuando durante una semana se organizan actividades y actos de todo tipo, para grandes y peque\u00f1os: carreras, gymkanas, talleres, bailes nocturnos, concursos&#8230;<\/p><p>El baile m\u00e1s representativo del Valle de Ar\u00e1n es el <strong><em>baile de la alborada o aubada<\/em><\/strong>.<\/p><p>Para conservar el patrimonio musical y de danza, se cre\u00f3 el grupo de Danzas Tradicionales Aranesas &#8216;<strong>Es Fardins de Vielha&#8217;<\/strong>, en el a\u00f1o 1988, y act\u00faan en varios pueblos del Valle durante agosto para difundir este patrimonio entre los visitantes.<\/p><h2>Mejor momento para visitar<\/h2><p>Sea verano o invierno, no pierdas la oportunidad de visitar Vielha, la ciudad m\u00e1s cosmopolita del Valle de Ar\u00e1n, donde el encanto de los Pirineos se fusiona con el bullicio del turismo.<\/p><h2>Imprescindibles<\/h2><ul><li class=\"DUwDvf lfPIob\">Descubrir la iglesia de San Miquel<\/li><li>Ver las casas medievales de Vielha<\/li><li>Acerca\u0301rse a la fuente con el escudo de Ar\u00e1n<\/li><li>Cruzar los puentes antiguos de Vielha<\/li><li>Conocer los bailes tradicionales araneses.<\/li><li>Recorrer los pueblos de los alrededores y los caminos que los conectan.<\/li><\/ul><h2>Qu\u00e9 ver cerca<\/h2><p>Los pueblos cercanos a Vielha tambi\u00e9n tienen iglesias con mucho valor patrimonial que vale la pena visitar. Estas son la <strong>Iglesia de San Andr\u00e9s de Casau<\/strong> de origen rom\u00e1nico y con una imagen de la Virgen de transici\u00f3n al g\u00f3tico y un retablo de la pasi\u00f3n.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27210\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-esglesia-sant-andreu-casau-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-andreu-casau-1024x768.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-andreu-casau-300x225.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-andreu-casau-768x576.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-andreu-casau.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Tambi\u00e9n de origen rom\u00e1nico es la <strong>Iglesia de Santa Mar\u00eda de Mijaran<\/strong>, un antiguo convento agustiniano, se dice que construido sobre un templo pagano.<\/p><p>La <strong>Iglesia San Mart\u00edn de Gausac<\/strong>, una iglesia g\u00f3tica del siglo XIV con elementos de finales del rom\u00e1nico. El elemento arquitect\u00f3nico m\u00e1s destacado es el campanario, del siglo XV, una torre g\u00f3tica fortificada que debi\u00f3 haber servido para uso defensivo.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27214\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-esglesia-sant-martin-gausac-1024x684.jpg\" alt=\"\" width=\"1024\" height=\"684\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-martin-gausac-1024x684.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-martin-gausac-300x200.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-martin-gausac-768x513.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-esglesia-sant-martin-gausac.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Uno de los lugares m\u00e1s cercanos a Vielha que vale la pena visitar es la <strong>Laguna de Oles y bosque de Varicauba<\/strong>. Este paraje se encuentra a pocos kil\u00f3metros de Vielha y se puede disfrutar del lago y de la vegetaci\u00f3n que lo rodea durante todo el a\u00f1o. El lago se puede rodear caminando en aproximadamente 20 minutos y este lugar es muy frecuentado por familias que deciden ir para pasar el d\u00eda y relajarse lejos de la civilizaci\u00f3n. Adem\u00e1s, desde la Laguna se pueden tomar dos <strong>circuitos de BTT<\/strong> (uno verde y otro azul) y los amantes de la pesca podr\u00e1n practicar la pesca intensiva de trucha de repoblaci\u00f3n si tienen el permiso adecuado.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27230\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/vielha-1-1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-1-1-1024x683.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-1-1-300x200.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-1-1-768x512.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/vielha-1-1.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>En el Valle de Ar\u00e1n hay muchos pueblos por conocer que os sorprender\u00e1n por su belleza: <strong>Arties<\/strong>, <strong>Boss\u00f2st<\/strong>, <a title=\"Qu\u00e9 hacer y qu\u00e9 ver en Canejan\" href=\"https:\/\/catalunyaturisme.cat\/es\/canejan\/\" target=\"_blank\" rel=\"noopener\"><strong>Canejan<\/strong><\/a>, <a title=\"Qu\u00e9 hacer y qu\u00e9 ver en Les\" href=\"https:\/\/catalunyaturisme.cat\/es\/les\/\" target=\"_blank\" rel=\"noopener\"><strong>Les<\/strong><\/a>, <strong>Bagergue<\/strong>\u2026 todos tienen su encanto!<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-27246\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/arties-3-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/arties-3-1024x768.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/arties-3-300x225.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/arties-3-768x576.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/arties-3.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><p>Tambi\u00e9n os recomendamos el maravilloso paisaje del <strong><a title=\"Parque Natural de Aig\u00fcestortes y el Estanque de San Mauricio\" href=\"https:\/\/catalunyaturisme.cat\/es\/parque-nacional-aiguestortes\/\" target=\"_blank\" rel=\"noopener\">Parque Natural de Aig\u00fcestortes y el Estanque de San Mauricio<\/a><\/strong>.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-22369\" src=\"http:\/\/catalunyaturisme.cat\/wp-content\/uploads\/\/aiguestortes-7-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" title=\"\" srcset=\"https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/aiguestortes-7-1024x768.jpg 1024w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/aiguestortes-7-300x225.jpg 300w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/aiguestortes-7-768x576.jpg 768w, https:\/\/catalunyaturisme.cat\/wp-content\/uploads\/aiguestortes-7.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p><h2>C\u00f3mo llegar<\/h2><p><strong>Por carretera<\/strong>: se puede llegar por la A-2 desde Barcelona (4 h) y desde <a href=\"https:\/\/catalunyaturisme.cat\/es\/girona\/\" title=\"Girona, la que enamora\">Girona<\/a> por la C-25 (4 h 30 min), y despu\u00e9s tomar la N-230 desde Lleida (2 h 15 min). Tambi\u00e9n se puede llegar por Arag\u00f3n, por la autopista A-22.<\/p><p><strong>En transporte p\u00fablico<\/strong>: en autob\u00fas, se puede tomar un <em>Alsa<\/em> desde Barcelona o Lleida. Tambi\u00e9n se puede llegar hasta Lleida y de ah\u00ed tomar el tren hasta las principales ciudades y pueblos de Catalu\u00f1a. Desde Vielha, tambi\u00e9n tiene parada la l\u00ednea de autob\u00fas Eth P\u00f2nt de Rei &#8211; Lleida, de la empresa <em>Alsina.<\/em><\/p><h2>Mapa<\/h2>\t\t<div id=\"maps-marker-pro-3559529f\" class=\"maps-marker-pro\" style=\"width: 100%;\">\t\t\t<div id=\"mmp-map-wrap-3559529f\" class=\"mmp-map-wrap\">\t\t\t\t\t\t\t\t<div id=\"mmp-map-3559529f\" class=\"mmp-map\" style=\"height: 600px;\"><\/div>\t\t\t\t\t\t\t<\/div>\t\t\t\t\t<\/div>\t\t","protected":false},"excerpt":{"rendered":"<p>Vielha, la capital del Valle de Ar\u00e1n, es una villa pirenaica que se encuentra a casi 1.000 metros de altitud y est\u00e1 rodeada de picos que superan los 2.000 metros. &hellip;<\/p>\n","protected":false},"author":1,"featured_media":27237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[781,617,1006,1065],"tags":[1017,1099,1018,1117,1253,1119],"class_list":["post-12058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vall-daran","category-ciudades-y-pueblos","category-destacado","category-lerida-provincia","tag-cultura-es","tag-esports-daventura-es-2","tag-historia-es","tag-natura-es-2","tag-pirineus-es","tag-senderisme-es-2"],"_links":{"self":[{"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/posts\/12058"}],"collection":[{"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/comments?post=12058"}],"version-history":[{"count":0,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/posts\/12058\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/media\/27237"}],"wp:attachment":[{"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/media?parent=12058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/categories?post=12058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catalunyaturisme.cat\/es\/wp-json\/wp\/v2\/tags?post=12058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}